{"id":8006,"date":"2024-06-05T15:43:16","date_gmt":"2024-06-05T13:43:16","guid":{"rendered":"https:\/\/copex.com\/partenaire\/btc-tsanaktsidis-bros\/"},"modified":"2024-07-03T08:36:28","modified_gmt":"2024-07-03T06:36:28","slug":"btc-tsanaktsidis-bros","status":"publish","type":"partenaire","link":"https:\/\/copex.com\/es\/socios\/btc-tsanaktsidis-bros\/","title":{"rendered":"BTC-Tsanaktsidis Bros- GRECIA, CHIPRE y ALABANIA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tras la adquisici\u00f3n de COPEX por el Grupo LEFORT, BTC-Tsanaktsidis Bros es su interlocutor privilegiado para sus necesidades de prensas cizallas en GRECIA, CHIPRE y ALBANIA.<\/p>\n","protected":false},"template":"","class_list":["post-8006","partenaire","type-partenaire","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BTC-Tsanaktsidis Bros- GRECIA, CHIPRE y ALABANIA - Copex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/copex.com\/es\/socios\/btc-tsanaktsidis-bros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BTC-Tsanaktsidis Bros- GRECIA, CHIPRE y ALABANIA - Copex\" \/>\n<meta property=\"og:description\" content=\"Tras la adquisici\u00f3n de COPEX por el Grupo LEFORT, BTC-Tsanaktsidis Bros es su interlocutor privilegiado para sus necesidades de prensas cizallas en GRECIA, CHIPRE y ALBANIA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/copex.com\/es\/socios\/btc-tsanaktsidis-bros\/\" \/>\n<meta property=\"og:site_name\" content=\"Copex\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-03T06:36:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/socios\\\/btc-tsanaktsidis-bros\\\/\",\"url\":\"https:\\\/\\\/copex.com\\\/es\\\/socios\\\/btc-tsanaktsidis-bros\\\/\",\"name\":\"BTC-Tsanaktsidis Bros- GRECIA, CHIPRE y ALABANIA - Copex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/#website\"},\"datePublished\":\"2024-06-05T13:43:16+00:00\",\"dateModified\":\"2024-07-03T06:36:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/socios\\\/btc-tsanaktsidis-bros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/copex.com\\\/es\\\/socios\\\/btc-tsanaktsidis-bros\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/socios\\\/btc-tsanaktsidis-bros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/copex.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Partenaires\",\"item\":\"https:\\\/\\\/copex.com\\\/es\\\/socios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BTC-Tsanaktsidis Bros- GRECIA, CHIPRE y ALABANIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/copex.com\\\/es\\\/\",\"name\":\"Copex\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/copex.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/#organization\",\"name\":\"copex\",\"url\":\"https:\\\/\\\/copex.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/copex.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-Logo-COPEX-@x2.jpg\",\"contentUrl\":\"https:\\\/\\\/copex.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-Logo-COPEX-@x2.jpg\",\"width\":457,\"height\":100,\"caption\":\"copex\"},\"image\":{\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BTC-Tsanaktsidis Bros- GRECIA, CHIPRE y ALABANIA - Copex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/copex.com\/es\/socios\/btc-tsanaktsidis-bros\/","og_locale":"es_ES","og_type":"article","og_title":"BTC-Tsanaktsidis Bros- GRECIA, CHIPRE y ALABANIA - Copex","og_description":"Tras la adquisici\u00f3n de COPEX por el Grupo LEFORT, BTC-Tsanaktsidis Bros es su interlocutor privilegiado para sus necesidades de prensas cizallas en GRECIA, CHIPRE y ALBANIA.","og_url":"https:\/\/copex.com\/es\/socios\/btc-tsanaktsidis-bros\/","og_site_name":"Copex","article_modified_time":"2024-07-03T06:36:28+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/copex.com\/es\/socios\/btc-tsanaktsidis-bros\/","url":"https:\/\/copex.com\/es\/socios\/btc-tsanaktsidis-bros\/","name":"BTC-Tsanaktsidis Bros- GRECIA, CHIPRE y ALABANIA - Copex","isPartOf":{"@id":"https:\/\/copex.com\/es\/#website"},"datePublished":"2024-06-05T13:43:16+00:00","dateModified":"2024-07-03T06:36:28+00:00","breadcrumb":{"@id":"https:\/\/copex.com\/es\/socios\/btc-tsanaktsidis-bros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/copex.com\/es\/socios\/btc-tsanaktsidis-bros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/copex.com\/es\/socios\/btc-tsanaktsidis-bros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/copex.com\/es\/"},{"@type":"ListItem","position":2,"name":"Partenaires","item":"https:\/\/copex.com\/es\/socios\/"},{"@type":"ListItem","position":3,"name":"BTC-Tsanaktsidis Bros- GRECIA, CHIPRE y ALABANIA"}]},{"@type":"WebSite","@id":"https:\/\/copex.com\/es\/#website","url":"https:\/\/copex.com\/es\/","name":"Copex","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/copex.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/copex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/copex.com\/es\/#organization","name":"copex","url":"https:\/\/copex.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/copex.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/copex.com\/wp-content\/uploads\/2020\/03\/cropped-Logo-COPEX-@x2.jpg","contentUrl":"https:\/\/copex.com\/wp-content\/uploads\/2020\/03\/cropped-Logo-COPEX-@x2.jpg","width":457,"height":100,"caption":"copex"},"image":{"@id":"https:\/\/copex.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/copex.com\/es\/wp-json\/wp\/v2\/partenaire\/8006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/copex.com\/es\/wp-json\/wp\/v2\/partenaire"}],"about":[{"href":"https:\/\/copex.com\/es\/wp-json\/wp\/v2\/types\/partenaire"}],"wp:attachment":[{"href":"https:\/\/copex.com\/es\/wp-json\/wp\/v2\/media?parent=8006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}