{"id":63,"count":4,"description":"","link":"https:\/\/copex.com\/es\/evenement_type\/salon-2-es\/","name":"Salon \/ Trade Fair","slug":"salon-2-es","taxonomy":"evenement_type","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Salon \/ Trade Fair - Copex<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Salon \/ Trade Fair - Copex\" \/>\n<meta property=\"og:url\" content=\"https:\/\/copex.com\/es\/evenement_type\/salon-2-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Copex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/evenement_type\\\/salon-2-es\\\/\",\"url\":\"https:\\\/\\\/copex.com\\\/es\\\/evenement_type\\\/salon-2-es\\\/\",\"name\":\"Archives des Salon \\\/ Trade Fair - Copex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/evenement_type\\\/salon-2-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/evenement_type\\\/salon-2-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/copex.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salon \\\/ Trade Fair\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/copex.com\\\/es\\\/\",\"name\":\"Copex\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/copex.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/#organization\",\"name\":\"copex\",\"url\":\"https:\\\/\\\/copex.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/copex.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-Logo-COPEX-@x2.jpg\",\"contentUrl\":\"https:\\\/\\\/copex.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-Logo-COPEX-@x2.jpg\",\"width\":457,\"height\":100,\"caption\":\"copex\"},\"image\":{\"@id\":\"https:\\\/\\\/copex.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Salon \/ Trade Fair - Copex","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Archives des Salon \/ Trade Fair - Copex","og_url":"https:\/\/copex.com\/es\/evenement_type\/salon-2-es\/","og_site_name":"Copex","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/copex.com\/es\/evenement_type\/salon-2-es\/","url":"https:\/\/copex.com\/es\/evenement_type\/salon-2-es\/","name":"Archives des Salon \/ Trade Fair - Copex","isPartOf":{"@id":"https:\/\/copex.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/copex.com\/es\/evenement_type\/salon-2-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/copex.com\/es\/evenement_type\/salon-2-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/copex.com\/es\/"},{"@type":"ListItem","position":2,"name":"Salon \/ Trade Fair"}]},{"@type":"WebSite","@id":"https:\/\/copex.com\/es\/#website","url":"https:\/\/copex.com\/es\/","name":"Copex","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/copex.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/copex.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/copex.com\/es\/#organization","name":"copex","url":"https:\/\/copex.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/copex.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/copex.com\/wp-content\/uploads\/2020\/03\/cropped-Logo-COPEX-@x2.jpg","contentUrl":"https:\/\/copex.com\/wp-content\/uploads\/2020\/03\/cropped-Logo-COPEX-@x2.jpg","width":457,"height":100,"caption":"copex"},"image":{"@id":"https:\/\/copex.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/copex.com\/es\/wp-json\/wp\/v2\/evenement_type\/63","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/copex.com\/es\/wp-json\/wp\/v2\/evenement_type"}],"about":[{"href":"https:\/\/copex.com\/es\/wp-json\/wp\/v2\/taxonomies\/evenement_type"}],"wp:post_type":[{"href":"https:\/\/copex.com\/es\/wp-json\/wp\/v2\/evenement?evenement_type=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}